{"id":75,"count":2,"description":"","link":"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/","name":"News","slug":"news-sl","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>News Archivi - Base Hotel - Noventa di Piave<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News Archivi - Base Hotel - Noventa di Piave\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/\" \/>\n<meta property=\"og:site_name\" content=\"Base Hotel - Noventa di Piave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/\",\"url\":\"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/\",\"name\":\"News Archivi - Base Hotel - Noventa di Piave\",\"isPartOf\":{\"@id\":\"https:\/\/www.basehotel.it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/#breadcrumb\"},\"inLanguage\":\"sl-SI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.basehotel.it\/sl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.basehotel.it\/#website\",\"url\":\"https:\/\/www.basehotel.it\/\",\"name\":\"Base Hotel - Noventa di Piave\",\"description\":\"I Base Hotel sono business e leisure hotel a Noventa di Piave, realizzati con particolar attenzione al design.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.basehotel.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"sl-SI\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News Archivi - Base Hotel - Noventa di Piave","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/","og_locale":"sl_SI","og_type":"article","og_title":"News Archivi - Base Hotel - Noventa di Piave","og_url":"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/","og_site_name":"Base Hotel - Noventa di Piave","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/","url":"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/","name":"News Archivi - Base Hotel - Noventa di Piave","isPartOf":{"@id":"https:\/\/www.basehotel.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/#breadcrumb"},"inLanguage":"sl-SI"},{"@type":"BreadcrumbList","@id":"https:\/\/www.basehotel.it\/sl\/category\/news-sl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.basehotel.it\/sl\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/www.basehotel.it\/#website","url":"https:\/\/www.basehotel.it\/","name":"Base Hotel - Noventa di Piave","description":"I Base Hotel sono business e leisure hotel a Noventa di Piave, realizzati con particolar attenzione al design.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.basehotel.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"sl-SI"}]}},"_links":{"self":[{"href":"https:\/\/www.basehotel.it\/sl\/wp-json\/wp\/v2\/categories\/75"}],"collection":[{"href":"https:\/\/www.basehotel.it\/sl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.basehotel.it\/sl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.basehotel.it\/sl\/wp-json\/wp\/v2\/posts?categories=75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}